{"id":826,"count":46,"description":"Armes R\u00e9pliques de l\u2019Ouest Inspir\u00e9es du Far West\nD\u00e9couvrez notre gamme d\u2019armes r\u00e9pliques de l\u2019Ouest, inspir\u00e9es du Far West et de la culture am\u00e9ricaine historique. Ces r\u00e9pliques western sont id\u00e9ales pour les collectionneurs, la d\u00e9coration th\u00e9matique ou comme cadeaux uniques. Fabriqu\u00e9es avec un soin particulier pour le r\u00e9alisme et les d\u00e9tails authentiques.","link":"https:\/\/jjcustomworks.se\/fr\/categorie-de-produit\/autres_produits\/replica-guns\/replica-western\/","name":"R\u00c9PLIQUES D&#039;ARMES OCCIDENTALES","slug":"replica-western","taxonomy":"product_cat","parent":823,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/jjcustomworks.se\/fr\/wp-json\/wp\/v2\/product_cat\/826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jjcustomworks.se\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/jjcustomworks.se\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/jjcustomworks.se\/fr\/wp-json\/wp\/v2\/product_cat\/823"}],"wp:post_type":[{"href":"https:\/\/jjcustomworks.se\/fr\/wp-json\/wp\/v2\/product?product_cat=826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}